{"id":1463,"date":"2024-05-10T17:39:44","date_gmt":"2024-05-10T15:39:44","guid":{"rendered":"https:\/\/aesisladolcecollina.com\/camere\/zimmer-2\/"},"modified":"2024-06-19T10:09:30","modified_gmt":"2024-06-19T08:09:30","slug":"zimmer-2","status":"publish","type":"camere","link":"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/","title":{"rendered":"Zimmer 2"},"content":{"rendered":"<p>Dieses Doppelzimmer befindet sich im ersten Stock des B&#038;B. Es hat ein Fenster mit Blick auf den Garten und verf\u00fcgt \u00fcber ein standardm\u00e4\u00dfiges <strong>Doppelbett<\/strong> mit der M\u00f6glichkeit, ein <strong>Einzelbett f\u00fcr einen Aufpreis von 25 \u20ac<\/strong> hinzuzuf\u00fcgen. Das Badezimmer ist privat und hat ein Fenster; es verf\u00fcgt au\u00dferdem \u00fcber alle <strong>Standardannehmlichkeiten<\/strong>, wie einen Haartrockner, Badem\u00e4ntel und Handt\u00fccher sowie Toilettenartikel.<br \/>\nF\u00fcr l\u00e4ngere Aufenthalte und f\u00fcr Kinder unter 4 Jahren werden <strong>Rabatte<\/strong> gew\u00e4hrt.<\/p>\n","protected":false},"featured_media":1390,"template":"","servizi_camere":[44,54,52,50,48,46,42,40],"class_list":["post-1463","camere","type-camere","status-publish","has-post-thumbnail","hentry","servizi_camere-fruhstuck","servizi_camere-geteilter-entspannungsraum","servizi_camere-zugang-zum-garten","servizi_camere-kostenlose-parkplatze","servizi_camere-badezimmer-set","servizi_camere-wifi-de-2","servizi_camere-tv-de-2","servizi_camere-klimatisierung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zimmer 2 - Aesis La Dolce Collina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zimmer 2 - Aesis La Dolce Collina\" \/>\n<meta property=\"og:description\" content=\"Dieses Doppelzimmer befindet sich im ersten Stock des B&#038;B. Es hat ein Fenster mit Blick auf den Garten und verf\u00fcgt \u00fcber ein standardm\u00e4\u00dfiges Doppelbett mit der M\u00f6glichkeit, ein Einzelbett f\u00fcr einen Aufpreis von 25 \u20ac hinzuzuf\u00fcgen. Das Badezimmer ist privat und hat ein Fenster; es verf\u00fcgt au\u00dferdem \u00fcber alle Standardannehmlichkeiten, wie einen Haartrockner, Badem\u00e4ntel und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Aesis La Dolce Collina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Aesis-La-Dolce-Collina\/100072191174463\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-19T08:09:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aesisladolcecollina.com\/wp-content\/uploads\/2024\/05\/camera-2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/\",\"url\":\"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/\",\"name\":\"Zimmer 2 - Aesis La Dolce Collina\",\"isPartOf\":{\"@id\":\"https:\/\/aesisladolcecollina.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/aesisladolcecollina.com\/wp-content\/uploads\/2024\/05\/camera-2.webp\",\"datePublished\":\"2024-05-10T15:39:44+00:00\",\"dateModified\":\"2024-06-19T08:09:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/#primaryimage\",\"url\":\"https:\/\/aesisladolcecollina.com\/wp-content\/uploads\/2024\/05\/camera-2.webp\",\"contentUrl\":\"https:\/\/aesisladolcecollina.com\/wp-content\/uploads\/2024\/05\/camera-2.webp\",\"width\":900,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/aesisladolcecollina.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zimmer\",\"item\":\"https:\/\/aesisladolcecollina.com\/de\/zimmer\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zimmer 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aesisladolcecollina.com\/de\/#website\",\"url\":\"https:\/\/aesisladolcecollina.com\/de\/\",\"name\":\"Aesis La Dolce Collina\",\"description\":\"Aesis, dove il relax incontra il gusto.\",\"publisher\":{\"@id\":\"https:\/\/aesisladolcecollina.com\/de\/#organization\"},\"alternateName\":\"B&B Aesis La Dolce Collina\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aesisladolcecollina.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/aesisladolcecollina.com\/de\/#organization\",\"name\":\"Aesis La Dolce Collina\",\"alternateName\":\"B&B Aesis La Dolce Collina\",\"url\":\"https:\/\/aesisladolcecollina.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/aesisladolcecollina.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/aesisladolcecollina.com\/wp-content\/uploads\/2024\/06\/logo-aesis.svg\",\"contentUrl\":\"https:\/\/aesisladolcecollina.com\/wp-content\/uploads\/2024\/06\/logo-aesis.svg\",\"width\":393,\"height\":116,\"caption\":\"Aesis La Dolce Collina\"},\"image\":{\"@id\":\"https:\/\/aesisladolcecollina.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/people\/Aesis-La-Dolce-Collina\/100072191174463\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zimmer 2 - Aesis La Dolce Collina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/","og_locale":"de_DE","og_type":"article","og_title":"Zimmer 2 - Aesis La Dolce Collina","og_description":"Dieses Doppelzimmer befindet sich im ersten Stock des B&#038;B. Es hat ein Fenster mit Blick auf den Garten und verf\u00fcgt \u00fcber ein standardm\u00e4\u00dfiges Doppelbett mit der M\u00f6glichkeit, ein Einzelbett f\u00fcr einen Aufpreis von 25 \u20ac hinzuzuf\u00fcgen. Das Badezimmer ist privat und hat ein Fenster; es verf\u00fcgt au\u00dferdem \u00fcber alle Standardannehmlichkeiten, wie einen Haartrockner, Badem\u00e4ntel und [&hellip;]","og_url":"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/","og_site_name":"Aesis La Dolce Collina","article_publisher":"https:\/\/www.facebook.com\/people\/Aesis-La-Dolce-Collina\/100072191174463\/","article_modified_time":"2024-06-19T08:09:30+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/aesisladolcecollina.com\/wp-content\/uploads\/2024\/05\/camera-2.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/","url":"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/","name":"Zimmer 2 - Aesis La Dolce Collina","isPartOf":{"@id":"https:\/\/aesisladolcecollina.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/#primaryimage"},"image":{"@id":"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/#primaryimage"},"thumbnailUrl":"https:\/\/aesisladolcecollina.com\/wp-content\/uploads\/2024\/05\/camera-2.webp","datePublished":"2024-05-10T15:39:44+00:00","dateModified":"2024-06-19T08:09:30+00:00","breadcrumb":{"@id":"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/#primaryimage","url":"https:\/\/aesisladolcecollina.com\/wp-content\/uploads\/2024\/05\/camera-2.webp","contentUrl":"https:\/\/aesisladolcecollina.com\/wp-content\/uploads\/2024\/05\/camera-2.webp","width":900,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/aesisladolcecollina.com\/de\/zimmer\/zimmer-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aesisladolcecollina.com\/de\/"},{"@type":"ListItem","position":2,"name":"Zimmer","item":"https:\/\/aesisladolcecollina.com\/de\/zimmer\/"},{"@type":"ListItem","position":3,"name":"Zimmer 2"}]},{"@type":"WebSite","@id":"https:\/\/aesisladolcecollina.com\/de\/#website","url":"https:\/\/aesisladolcecollina.com\/de\/","name":"Aesis La Dolce Collina","description":"Aesis, dove il relax incontra il gusto.","publisher":{"@id":"https:\/\/aesisladolcecollina.com\/de\/#organization"},"alternateName":"B&B Aesis La Dolce Collina","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aesisladolcecollina.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aesisladolcecollina.com\/de\/#organization","name":"Aesis La Dolce Collina","alternateName":"B&B Aesis La Dolce Collina","url":"https:\/\/aesisladolcecollina.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aesisladolcecollina.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/aesisladolcecollina.com\/wp-content\/uploads\/2024\/06\/logo-aesis.svg","contentUrl":"https:\/\/aesisladolcecollina.com\/wp-content\/uploads\/2024\/06\/logo-aesis.svg","width":393,"height":116,"caption":"Aesis La Dolce Collina"},"image":{"@id":"https:\/\/aesisladolcecollina.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Aesis-La-Dolce-Collina\/100072191174463\/"]}]}},"_links":{"self":[{"href":"https:\/\/aesisladolcecollina.com\/de\/wp-json\/wp\/v2\/camere\/1463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aesisladolcecollina.com\/de\/wp-json\/wp\/v2\/camere"}],"about":[{"href":"https:\/\/aesisladolcecollina.com\/de\/wp-json\/wp\/v2\/types\/camere"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aesisladolcecollina.com\/de\/wp-json\/wp\/v2\/media\/1390"}],"wp:attachment":[{"href":"https:\/\/aesisladolcecollina.com\/de\/wp-json\/wp\/v2\/media?parent=1463"}],"wp:term":[{"taxonomy":"servizi_camere","embeddable":true,"href":"https:\/\/aesisladolcecollina.com\/de\/wp-json\/wp\/v2\/servizi_camere?post=1463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}